{"id":4047,"date":"2025-11-05T09:54:12","date_gmt":"2025-11-05T08:54:12","guid":{"rendered":"https:\/\/garcialegaz.com\/?page_id=3947"},"modified":"2026-02-12T23:13:02","modified_gmt":"2026-02-12T22:13:02","slug":"renewal-of-medical-prescriptions","status":"publish","type":"page","link":"https:\/\/garcialegaz.com\/en\/renewal-of-medical-prescriptions\/","title":{"rendered":"Renewal of medical prescriptions"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"4047\" class=\"elementor elementor-4047\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-679a24bf e-flex e-con-boxed e-con e-parent\" data-id=\"679a24bf\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-65b8919e e-con-full e-flex e-con e-child\" data-id=\"65b8919e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6ac17066 elementor-widget elementor-widget-heading\" data-id=\"6ac17066\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 id=\"rtoc-1\"  class=\"elementor-heading-title elementor-size-default\">Renovaci\u00f3n de recetas m\u00e9dicas\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ac39ed0 elementor-align-left elementor-mobile-align-left elementor-widget elementor-widget-button\" data-id=\"2ac39ed0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-grow\" href=\"#solicitar\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Solicitar<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6dfbdf7 e-con-full e-flex e-con e-child\" data-id=\"6dfbdf7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-594d8ffa elementor-widget__width-initial animated-slow elementor-widget-divider--view-line_text elementor-widget-divider--element-align-left elementor-widget-mobile__width-inherit elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"594d8ffa\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:&quot;200&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<span class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\t01\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7026ba47 elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"7026ba47\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 id=\"rtoc-2\"  class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tRellena el formulario\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tSi alguno de nuestros dermat\u00f3logos ya te han hecho una receta podr\u00e1s renovarlas desde este formulario.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-89a7530 e-con-full e-flex e-con e-child\" data-id=\"89a7530\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b96272a elementor-widget__width-initial animated-slow elementor-widget-divider--view-line_text elementor-widget-divider--element-align-left elementor-widget-mobile__width-inherit elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"4b96272a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_delay&quot;:&quot;200&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t\t<span class=\"elementor-divider__text elementor-divider__element\">\n\t\t\t\t02\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-445bb25c elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"445bb25c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 id=\"rtoc-3\"  class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tRecibe las recetas en tu correo electr\u00f3nico\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tEn un plazo aproximado de 5 d\u00edas.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-39ee7359 e-con-full e-flex e-con e-parent\" data-id=\"39ee7359\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-2a47b1a0 e-con-full elementor-hidden-mobile e-flex e-con e-child\" data-id=\"2a47b1a0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_scale_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_scale_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:50,&quot;end&quot;:100}},&quot;background_motion_fx_scale_direction&quot;:&quot;out-in&quot;,&quot;background_motion_fx_scale_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\">\n\t\t<div class=\"elementor-element elementor-element-4b453f37 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"4b453f37\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation&quot;:&quot;slideInRight&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4170dd9c elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"4170dd9c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/garcialegaz.com\/wp-content\/uploads\/2024\/06\/equipo-garcia-legaz.webp\" class=\" attachment-full size-full wp-image-1843\" alt=\"Equipo Cl\u00ednica Dermatol\u00f3gica Garc\u00eda-Legaz (Murcia)\" srcset=\"https:\/\/garcialegaz.com\/wp-content\/uploads\/2024\/06\/equipo-garcia-legaz.webp 1000w, https:\/\/garcialegaz.com\/wp-content\/uploads\/2024\/06\/equipo-garcia-legaz-300x300.webp 300w, https:\/\/garcialegaz.com\/wp-content\/uploads\/2024\/06\/equipo-garcia-legaz-150x150.webp 150w, https:\/\/garcialegaz.com\/wp-content\/uploads\/2024\/06\/equipo-garcia-legaz-768x768.webp 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-15aef530 elementor-widget elementor-widget-image-box\" data-id=\"15aef530\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-box-wrapper\"><div class=\"elementor-image-box-content\"><h5 class=\"elementor-image-box-title\">Instituto Dermatol\u00f3gico Garc\u00eda-Legaz<\/h5><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3733778b elementor-widget elementor-widget-heading\" data-id=\"3733778b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Un equipo de dermat\u00f3logos con la \u00faltima tecnolog\u00eda , el mayor grado de profesionalidad y cercan\u00eda en nuestra cl\u00ednica dermatol\u00f3gica de Murcia .\n\n<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-35f8208e elementor-widget elementor-widget-button\" data-id=\"35f8208e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/garcialegaz.com\/equipo\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Ver equipo<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-73269625 e-con-full e-flex e-con e-child\" data-id=\"73269625\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-578b03a7 elementor-widget elementor-widget-heading\" data-id=\"578b03a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Renueva tu, <br><b>receta m\u00e9dica<\/b><\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d084a52 elementor-widget elementor-widget-heading\" data-id=\"d084a52\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 id=\"rtoc-4\"  class=\"elementor-heading-title elementor-size-default\">15,00\u20ac<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22e1e006 elementor-tablet-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"22e1e006\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-shrink\" href=\"#solicitar\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Solicitar<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7f7a9ff e-con-full e-flex e-con e-child\" data-id=\"7f7a9ff\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-383dce8 elementor-widget elementor-widget-text-editor\" data-id=\"383dce8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Solo se emitir\u00e1n recetas previamente indicadas por alguno de nuestros dermat\u00f3logos en consulta, no se realizar\u00e1n nuevas prescripciones<\/li><li>Tiempo respuesta no garantizado antes de 7 d\u00edas.<\/li><li>Rellena los espacios con los datos DEL\/LA PACIENTE menor de edad y no del\/la tutor\/a o padre\/madre.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-19bbbc7 e-flex e-con-boxed e-con e-parent\" data-id=\"19bbbc7\" data-element_type=\"container\" data-e-type=\"container\" id=\"solicitar\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8748a28 elementor-alert-info elementor-widget elementor-widget-alert\" data-id=\"8748a28\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"alert.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-alert\" role=\"alert\">\n\n\t\t\t\t\t\t<span class=\"elementor-alert-title\">Informaci\u00f3n<\/span>\n\t\t\t\n\t\t\t\t\t\t<span class=\"elementor-alert-description\">Tras realizar el pago podr\u00e1s rellenar el formulario con tu consulta<\/span>\n\t\t\t\n\t\t\t\t\t\t<button type=\"button\" class=\"elementor-alert-dismiss\" aria-label=\"Dismiss this alert.\">\n\t\t\t\t\t\t\t\t\t<span aria-hidden=\"true\">&times;<\/span>\n\t\t\t\t\t\t\t<\/button>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5244bdc elementor-widget elementor-widget-shortcode\" data-id=\"5244bdc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\"><style id=\"wpforms-css-vars-3953\">\n\t\t\t\t#wpforms-3953 {\n\t\t\t\t--wpforms-field-border-color: rgba(0, 0, 0, 0.25);\n--wpforms-field-border-color-spare: rgba(0, 0, 0, 0.25);\n--wpforms-field-text-color: rgba(0, 0, 0, 0.7);\n--wpforms-label-color: rgba(0, 0, 0, 0.85);\n--wpforms-label-sublabel-color: rgba(0, 0, 0, 0.55);\n--wpforms-button-background-color: #000000;\n--wpforms-background-color: rgba(0, 0, 0, 0);\n--wpforms-field-size-input-height: 43px;\n--wpforms-field-size-input-spacing: 15px;\n--wpforms-field-size-font-size: 16px;\n--wpforms-field-size-line-height: 19px;\n--wpforms-field-size-padding-h: 14px;\n--wpforms-field-size-checkbox-size: 16px;\n--wpforms-field-size-sublabel-spacing: 5px;\n--wpforms-field-size-icon-size: 1;\n--wpforms-label-size-font-size: 16px;\n--wpforms-label-size-line-height: 19px;\n--wpforms-label-size-sublabel-font-size: 14px;\n--wpforms-label-size-sublabel-line-height: 17px;\n--wpforms-button-size-font-size: 17px;\n--wpforms-button-size-height: 41px;\n--wpforms-button-size-padding-h: 15px;\n--wpforms-button-size-margin-top: 10px;\n--wpforms-container-shadow-size-box-shadow: none;\n\t\t\t}\n\t\t\t<\/style><div class=\"wpforms-container wpforms-container-full wpforms-stripe wpforms-render-modern\" id=\"wpforms-3953\"><form id=\"wpforms-form-3953\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"3953\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/4047\" data-token=\"9fd313b77d81c324fc058213c49b49c1\" data-token-time=\"1778696383\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Please enable JavaScript in your browser to complete this form.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-3953-field_3-container\" class=\"wpforms-field wpforms-field-select wpforms-conditional-trigger wpforms-field-select-style-modern\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-3953-field_3\">\u00bfTe hemos generado ya alguna receta o es una nueva prescripci\u00f3n? <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><select id=\"wpforms-3953-field_3\" class=\"wpforms-field-large wpforms-field-required choicesjs-select\" data-size-class=\"wpforms-field-row wpforms-field-large\" data-search-enabled=\"\" name=\"wpforms[fields][3]\" required=\"required\"><option value=\"\" class=\"placeholder\" disabled ><\/option><option value=\"-- Seleccionar --\"  selected='selected' class=\"choice-3 depth-1\"  >-- Seleccionar --<\/option><option value=\"Ya tengo receta y quiero renovarla\"  class=\"choice-1 depth-1\"  >Ya tengo receta y quiero renovarla<\/option><option value=\"No tengo receta\"  class=\"choice-2 depth-1\"  >No tengo receta<\/option><\/select><\/div><div id=\"wpforms-3953-field_20-container\" class=\"wpforms-field wpforms-field-email wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"20\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-3953-field_20\">Correo electr\u00f3nico <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-3953-field_20\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][20]\" spellcheck=\"false\" aria-errormessage=\"wpforms-3953-field_20-error\" required><\/div><div id=\"wpforms-3953-field_21-container\" class=\"wpforms-field wpforms-field-phone wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"21\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-3953-field_21\">Tel\u00e9fono<\/label><input type=\"tel\" id=\"wpforms-3953-field_21\" class=\"wpforms-field-large wpforms-smart-phone-field\" data-rule-smart-phone-field=\"true\" name=\"wpforms[fields][21]\" aria-label=\"Tel\u00e9fono\" aria-errormessage=\"wpforms-3953-field_21-error\" ><\/div><div id=\"wpforms-3953-field_4-container\" class=\"wpforms-field wpforms-field-text wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"4\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-3953-field_4\">Nombre (del paciente) <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-3953-field_4\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][4]\" aria-errormessage=\"wpforms-3953-field_4-error\" required><\/div><div id=\"wpforms-3953-field_5-container\" class=\"wpforms-field wpforms-field-text wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"5\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-3953-field_5\">Apellidos (del paciente) <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-3953-field_5\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][5]\" aria-errormessage=\"wpforms-3953-field_5-error\" required><\/div><div id=\"wpforms-3953-field_8-container\" class=\"wpforms-field wpforms-field-textarea wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"8\" style=\"display:none;\"><label class=\"wpforms-field-label\" for=\"wpforms-3953-field_8\">\u00bfQu\u00e9 recetas necesitas renovar?* <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><textarea id=\"wpforms-3953-field_8\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][8]\" aria-errormessage=\"wpforms-3953-field_8-error\" aria-describedby=\"wpforms-3953-field_8-description\" required><\/textarea><div id=\"wpforms-3953-field_8-description\" class=\"wpforms-field-description\">M\u00e1ximo 3 recetas<\/div><\/div><div id=\"wpforms-3953-field_18-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"18\" style=\"display:none;\"><fieldset><legend class=\"wpforms-field-label\">Aceptar condiciones <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-3953-field_18\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-3953-field_18_1\" name=\"wpforms[fields][18][]\" value=\"El\/la usuario\/a acepta que esta compra \u00fanicamente es v\u00e1lida para la renovaci\u00f3n de recetas de medicamentos en pacientes Garc\u00eda Legaz para recetas ya generadas previamente.\" aria-errormessage=\"wpforms-3953-field_18_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3953-field_18_1\">El\/la usuario\/a acepta que esta compra \u00fanicamente es v\u00e1lida para la renovaci\u00f3n de recetas de medicamentos en pacientes Garc\u00eda Legaz para recetas ya generadas previamente.<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-3953-field_22-container\" class=\"wpforms-field wpforms-field-payment-single wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"22\" style=\"display:none;\"><label class=\"wpforms-field-label\">Coste <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div class=\"wpforms-single-item-price-content\"><div class=\"wpforms-single-item-price wpforms-field-medium wpforms-field-required wpforms-payment-price\">Precio: <span class=\"wpforms-price\">15,00 &euro;<\/span><\/div><\/div><input type=\"hidden\" id=\"wpforms-3953-field_22\" class=\"wpforms-field-medium wpforms-field-required wpforms-payment-price\" data-rule-required-positive-number=\"1\" name=\"wpforms[fields][22]\" value=\"15,00 &euro;\"><\/div><div id=\"wpforms-3953-field_19-container\" class=\"wpforms-field wpforms-field-stripe-credit-card wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"19\" style=\"display:none;\"><label class=\"wpforms-field-label\">Pago <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-no-columns wpforms-field-large \" data-sublabel-position=\"above\" data-link-email=\"\" data-required=\"1\"><div id=\"wpforms-field-stripe-link-element-3953\"><\/div><div id=\"wpforms-field-stripe-payment-element-3953\"><\/div><input type=\"text\" class=\"wpforms-stripe-credit-card-hidden-input\" name=\"wpforms[stripe-credit-card-hidden-input-3953]\" disabled style=\"display: none;\"><\/div><\/div><div id=\"wpforms-3953-field_23-container\" class=\"wpforms-field wpforms-field-html wpforms-conditional-field wpforms-conditional-show\" data-field-id=\"23\" style=\"display:none;\"><div id=\"wpforms-3953-field_23\" aria-errormessage=\"wpforms-3953-field_23-error\"><p style=\"color:red;\">No es posible tramitar la renovaci\u00f3n de recetas si no han sido prescritas previamente por nuestro equipo.\r\n <\/p><\/div><\/div>\t\t<div id=\"wpforms-3953-field_1-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"1\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-3953-field_1\" >Correo una paciente)<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-3953-field_1\" class=\"wpforms-field-medium\" name=\"wpforms[fields][1]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-3953-field_24-container\" class=\"wpforms-field wpforms-field-html\" data-field-id=\"24\"><div id=\"wpforms-3953-field_24\" aria-errormessage=\"wpforms-3953-field_24-error\"><script>\r\ndocument.addEventListener('DOMContentLoaded', function() {\r\n    const selectField = document.getElementById('wpforms-3953-field_3');\r\n    const submitButton = document.querySelector('#wpforms-submit-3953');\r\n\r\n    if (selectField && submitButton) {\r\n        \/\/ Ocultamos el bot\u00f3n inicialmente\r\n        submitButton.style.display = 'none';\r\n\r\n        \/\/ Funci\u00f3n para mostrar\/ocultar seg\u00fan la opci\u00f3n seleccionada\r\n        const toggleSubmit = () => {\r\n            const selectedValue = selectField.value.trim();\r\n            if (selectedValue === 'Ya tengo receta y quiero renovarla') {\r\n                submitButton.style.display = 'inline-block';\r\n            } else {\r\n                submitButton.style.display = 'none';\r\n            }\r\n        };\r\n\r\n        \/\/ Detectar cambios (Choices.js actualiza el select internamente)\r\n        selectField.addEventListener('change', toggleSubmit);\r\n\r\n        \/\/ Ejecutar tambi\u00e9n al cargar, por si el campo ya tiene valor\r\n        toggleSubmit();\r\n    }\r\n});\r\n<\/script><\/div><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-3953-field_1-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-3953-field_1-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-3953-field_1-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"3953\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/garcialegaz.com\/en\/wp-json\/wp\/v2\/pages\/4047\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-3953\" class=\"wpforms-submit\" data-alt-text=\"Enviando...\" data-submit-text=\"Enviar\" aria-live=\"assertive\" value=\"wpforms-submit\">Enviar<\/button><img decoding=\"async\" src=\"https:\/\/garcialegaz.com\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container --><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-39d6a1fb e-con-full e-flex e-con e-parent\" data-id=\"39d6a1fb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-1cc22901 e-con-full e-flex e-con e-child\" data-id=\"1cc22901\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-64b786c8 elementor-widget elementor-widget-heading\" data-id=\"64b786c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 id=\"rtoc-5\"  class=\"elementor-heading-title elementor-size-default\">Preguntas <b>frecuentes<\/b>\n\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-84008ff elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"84008ff\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1154ff9f elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"1154ff9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Estas son algunas de las preguntas frecuentes que tienen nuestros clientes<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3497953d e-con-full e-flex e-con e-child\" data-id=\"3497953d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2dcc6d47 elementor-widget__width-inherit elementor-widget elementor-widget-toggle\" data-id=\"2dcc6d47\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h6 id=\"elementor-tab-title-7681\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-7681\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"bfdde3cf-e88c-4bbd-b388-4a5f99496140\" data-name=\"Layer 1\" width=\"18.707\" height=\"10.0645\" viewBox=\"0 0 18.707 10.0645\"><polygon points=\"17.992 0.008 9.546 8.65 0.699 0 0 0.715 9.562 10.064 18.707 0.707 17.992 0.008\"><\/polygon><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"a2fff8ba-a73e-477d-80d0-a10e90dbb221\" data-name=\"Layer 1\" width=\"18.707\" height=\"10.0645\" viewBox=\"0 0 18.707 10.0645\"><polygon points=\"9.146 0 0 9.357 0.715 10.057 9.161 1.414 18.008 10.064 18.707 9.35 9.146 0\"><\/polygon><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Si necesito renovar m\u00e1s de una receta \u00bftengo que hacer un pago por cada receta?<\/a>\n\t\t\t\t\t<\/h6>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-7681\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-7681\"><p>Con el pago de este servicio podr\u00e1s renovar un m\u00e1ximo de 3 recetas.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d5a46f9 elementor-widget__width-inherit elementor-widget elementor-widget-toggle\" data-id=\"d5a46f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<h6 id=\"elementor-tab-title-2241\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-2241\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"bfdde3cf-e88c-4bbd-b388-4a5f99496140\" data-name=\"Layer 1\" width=\"18.707\" height=\"10.0645\" viewBox=\"0 0 18.707 10.0645\"><polygon points=\"17.992 0.008 9.546 8.65 0.699 0 0 0.715 9.562 10.064 18.707 0.707 17.992 0.008\"><\/polygon><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" id=\"a2fff8ba-a73e-477d-80d0-a10e90dbb221\" data-name=\"Layer 1\" width=\"18.707\" height=\"10.0645\" viewBox=\"0 0 18.707 10.0645\"><polygon points=\"9.146 0 0 9.357 0.715 10.057 9.161 1.414 18.008 10.064 18.707 9.35 9.146 0\"><\/polygon><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">\u00bfEn cu\u00e1nto tiempo recibir\u00e9 mi receta?<\/a>\n\t\t\t\t\t<\/h6>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-2241\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-2241\"><p>Nos comprometemos enviarla en un plazo m\u00e1ximo de siete d\u00edas laborables a excepci\u00f3n de enfermedad, de per\u00edodos vacacionales o de festivos.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9063e91 e-flex e-con-boxed e-con e-parent\" data-id=\"9063e91\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-70e5b8f elementor-widget elementor-widget-spacer\" data-id=\"70e5b8f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Renovaci\u00f3n de recetas m\u00e9dicas Solicitar 01 Rellena el formulario Si alguno de nuestros dermat\u00f3logos ya te han hecho una receta podr\u00e1s renovarlas desde este formulario. 02 Recibe las recetas en tu correo electr\u00f3nico En un plazo aproximado de 5 d\u00edas. Instituto Dermatol\u00f3gico Garc\u00eda-Legaz Un equipo de dermat\u00f3logos con la \u00faltima tecnolog\u00eda , el mayor grado [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4047","page","type-page","status-publish","hentry"],"lang":"en","translations":{"en":4047,"es":3947},"_links":{"self":[{"href":"https:\/\/garcialegaz.com\/en\/wp-json\/wp\/v2\/pages\/4047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/garcialegaz.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/garcialegaz.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/garcialegaz.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/garcialegaz.com\/en\/wp-json\/wp\/v2\/comments?post=4047"}],"version-history":[{"count":1,"href":"https:\/\/garcialegaz.com\/en\/wp-json\/wp\/v2\/pages\/4047\/revisions"}],"predecessor-version":[{"id":11344,"href":"https:\/\/garcialegaz.com\/en\/wp-json\/wp\/v2\/pages\/4047\/revisions\/11344"}],"wp:attachment":[{"href":"https:\/\/garcialegaz.com\/en\/wp-json\/wp\/v2\/media?parent=4047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}